{"id":135,"count":1,"description":"","link":"http:\/\/s-lineedition.com\/blog\/tag\/why-car-lovers-love-dubai\/","name":"why car lovers love Dubai","slug":"why-car-lovers-love-dubai","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/s-lineedition.com\/blog\/wp-json\/wp\/v2\/tags\/135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/s-lineedition.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/s-lineedition.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/s-lineedition.com\/blog\/wp-json\/wp\/v2\/posts?tags=135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}